{"id":4038,"date":"2024-03-06T23:26:14","date_gmt":"2024-03-06T16:26:14","guid":{"rendered":"https:\/\/fba-hoops.com\/?post_type=staff&#038;p=4038"},"modified":"2024-03-10T09:48:06","modified_gmt":"2024-03-10T02:48:06","slug":"%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%97%e0%b8%b1%e0%b8%a7%e0%b8%a3%e0%b9%8c","status":"publish","type":"staff","link":"https:\/\/fba-hoops.com\/th\/staff\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%97%e0%b8%b1%e0%b8%a7%e0%b8%a3%e0%b9%8c\/","title":{"rendered":"\u0e04\u0e38\u0e13\u0e17\u0e31\u0e27\u0e23\u0e4c"},"featured_media":4153,"template":"","class_list":["post-4038","staff","type-staff","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/fba-hoops.com\/th\/wp-json\/wp\/v2\/staff\/4038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fba-hoops.com\/th\/wp-json\/wp\/v2\/staff"}],"about":[{"href":"https:\/\/fba-hoops.com\/th\/wp-json\/wp\/v2\/types\/staff"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fba-hoops.com\/th\/wp-json\/wp\/v2\/media\/4153"}],"wp:attachment":[{"href":"https:\/\/fba-hoops.com\/th\/wp-json\/wp\/v2\/media?parent=4038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}